{"id":7073,"date":"2023-10-25T18:38:11","date_gmt":"2023-10-25T17:38:11","guid":{"rendered":"https:\/\/emanuelenargi.com\/?page_id=7073"},"modified":"2023-11-29T17:34:52","modified_gmt":"2023-11-29T17:34:52","slug":"talleres-spanish","status":"publish","type":"page","link":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/","title":{"rendered":"TALLERES &#8211; Spanish"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7073\" class=\"elementor elementor-7073\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9edd4c e-flex e-con-boxed e-con e-parent\" data-id=\"e9edd4c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7805a7 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"f7805a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b6675c elementor-widget elementor-widget-image\" data-id=\"7b6675c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001.jpg\" class=\"attachment-full size-full wp-image-3884\" alt=\"\" srcset=\"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001.jpg 2048w, https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001-300x225.jpg 300w, https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001-1024x768.jpg 1024w, https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001-768x576.jpg 768w, https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/10\/IMG-20210901-WA0001-1536x1152.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">St. Gilgen, JUMBO, 2021<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-107bd41 e-con-full e-flex e-con e-child\" data-id=\"107bd41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d065359 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d065359\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>TALLERES<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4069e2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e4069e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">CREACI\u00d3N DE IDEAS<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df86af animated-slow elementor-invisible elementor-widget elementor-widget-toggle\" data-id=\"1df86af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Explore el mundo del teatro inmersivo<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3141\"><p><span style=\"font-weight: 400;\"><strong>Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo.<\/strong> Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><strong>Contenido del curso:<\/strong><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><ul><li><span style=\"font-weight: 400;\">Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la narraci\u00f3n interactiva y participativa y el arte de implicar al p\u00fablico.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><ul><li><span style=\"font-weight: 400;\">Exploraci\u00f3n espacial: estudio de las complejidades del espacio como elemento narrativo. Exploraci\u00f3n de t\u00e9cnicas site-specific, composici\u00f3n en 360\u00b0, distancia y observaci\u00f3n.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><ul><li><span style=\"font-weight: 400;\">Din\u00e1mica interactiva: interacciones, tareas y misiones. Conocimiento de los encuentros, adaptaci\u00f3n y asunci\u00f3n de riesgos.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><ul><li><span style=\"font-weight: 400;\">Teatro sensorial: implicaci\u00f3n de los sentidos como el tacto, el gusto y el olfato. Creaci\u00f3n de secuencias sensoriales que resuenen en el p\u00fablico. Profundizaci\u00f3n en conceptos como prox\u00e9mica e intimidad, creaci\u00f3n de experiencias individuales, tonos atmosf\u00e9ricos y esferas personales.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\"><strong>Requisitos de espacio:<\/strong> Lo ideal ser\u00eda un espacio amplio con varias salas de distintos tama\u00f1os y tipos.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n, p\u00f3ngase en contacto conmigo: info@emanuelenargi.com, +34602674049<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3142\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-3142\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Descubrimos juntos posibilidades creativas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3142\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-3142\"><p><span style=\"font-weight: 400;\"><strong>Acomp\u00e1\u00f1eme en un evento din\u00e1mico en el que exploraremos un sinf\u00edn de formatos de taller adaptables.<\/strong> Juntos podemos personalizar y crear diferentes experiencias de taller. Estoy abierto a un amplio abanico de posibilidades, para asegurarme de que creamos un espacio de aprendizaje adaptado a tus necesidades.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Ponte en contacto conmigo: info@emanuelenargi.com<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>St. Gilgen, JUMBO, 2021 TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. \u00a0 Contenido del curso: \u00a0 Teatro inmersivo: estudio en &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/\"> <span class=\"screen-reader-text\">TALLERES &#8211; Spanish<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7065,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"class_list":["post-7073","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EMANUELE NARGI -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TALLERES \u2013 Spanish - EMANUELE NARGI\" \/>\n\t\t<meta property=\"og:description\" content=\"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-25T17:38:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-29T17:34:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TALLERES \u2013 Spanish - EMANUELE NARGI\" \/>\n\t\t<meta name=\"twitter:description\" content=\"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/emanuelenargi.com\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/#listItem\",\"name\":\"FORMADOR &#8211; Spanish\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/#listItem\",\"position\":2,\"name\":\"FORMADOR &#8211; Spanish\",\"item\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/#listItem\",\"name\":\"SERVICIOS &#8211; Spanish\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/#listItem\",\"position\":3,\"name\":\"SERVICIOS &#8211; Spanish\",\"item\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#listItem\",\"name\":\"TALLERES &#8211; Spanish\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/#listItem\",\"name\":\"FORMADOR &#8211; Spanish\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#listItem\",\"position\":4,\"name\":\"TALLERES &#8211; Spanish\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/#listItem\",\"name\":\"SERVICIOS &#8211; Spanish\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#organization\",\"name\":\"emanuelenargi.com\",\"url\":\"https:\\\/\\\/emanuelenargi.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/emanuelenargi.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-EMANUELE_NARGI_EN__1_-removebg.png\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#organizationLogo\",\"width\":1413,\"height\":299},\"image\":{\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#webpage\",\"url\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/\",\"name\":\"TALLERES \\u2013 Spanish - EMANUELE NARGI\",\"description\":\"TALLERES CREACI\\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\\u00e9ntrese en el mundo del teatro inmersivo a trav\\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/index.php\\\/es\\\/formador-spanish\\\/servicios-spanish\\\/talleres-spanish\\\/#breadcrumblist\"},\"datePublished\":\"2023-10-25T18:38:11+01:00\",\"dateModified\":\"2023-11-29T17:34:52+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#website\",\"url\":\"https:\\\/\\\/emanuelenargi.com\\\/\",\"name\":\"emanuelenargi.com\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/emanuelenargi.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TALLERES \u2013 Spanish - EMANUELE NARGI","description":"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la","canonical_url":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/#listItem","position":1,"name":"Home","item":"https:\/\/emanuelenargi.com\/","nextItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/#listItem","name":"FORMADOR &#8211; Spanish"}},{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/#listItem","position":2,"name":"FORMADOR &#8211; Spanish","item":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/","nextItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/#listItem","name":"SERVICIOS &#8211; Spanish"},"previousItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/#listItem","position":3,"name":"SERVICIOS &#8211; Spanish","item":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/","nextItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#listItem","name":"TALLERES &#8211; Spanish"},"previousItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/#listItem","name":"FORMADOR &#8211; Spanish"}},{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#listItem","position":4,"name":"TALLERES &#8211; Spanish","previousItem":{"@type":"ListItem","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/#listItem","name":"SERVICIOS &#8211; Spanish"}}]},{"@type":"Organization","@id":"https:\/\/emanuelenargi.com\/#organization","name":"emanuelenargi.com","url":"https:\/\/emanuelenargi.com\/","logo":{"@type":"ImageObject","url":"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#organizationLogo","width":1413,"height":299},"image":{"@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#webpage","url":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/","name":"TALLERES \u2013 Spanish - EMANUELE NARGI","description":"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/emanuelenargi.com\/#website"},"breadcrumb":{"@id":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/#breadcrumblist"},"datePublished":"2023-10-25T18:38:11+01:00","dateModified":"2023-11-29T17:34:52+00:00"},{"@type":"WebSite","@id":"https:\/\/emanuelenargi.com\/#website","url":"https:\/\/emanuelenargi.com\/","name":"emanuelenargi.com","inLanguage":"en-GB","publisher":{"@id":"https:\/\/emanuelenargi.com\/#organization"}}]},"og:locale":"en_GB","og:site_name":"EMANUELE NARGI -","og:type":"article","og:title":"TALLERES \u2013 Spanish - EMANUELE NARGI","og:description":"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la","og:url":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/","og:image":"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png","og:image:secure_url":"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png","article:published_time":"2023-10-25T17:38:11+00:00","article:modified_time":"2023-11-29T17:34:52+00:00","twitter:card":"summary_large_image","twitter:title":"TALLERES \u2013 Spanish - EMANUELE NARGI","twitter:description":"TALLERES CREACI\u00d3N DE IDEAS Explore el mundo del teatro inmersivo Ad\u00e9ntrese en el mundo del teatro inmersivo a trav\u00e9s de un taller completo. Esta experiencia se desarrollas en encuentros tem\u00e1ticos para descubrir los elementos esenciales necesarios para crear espect\u00e1culos inmersivos e interactivos. Contenido del curso: Teatro inmersivo: estudio en profundidad de los distintos tipos de teatro, la","twitter:image":"https:\/\/emanuelenargi.com\/wp-content\/uploads\/2023\/09\/cropped-EMANUELE_NARGI_EN__1_-removebg.png"},"aioseo_meta_data":{"post_id":"7073","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-24 12:06:51","updated":"2025-09-24 05:02:25","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/emanuelenargi.com\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/\" title=\"FORMADOR \u2013 Spanish\">FORMADOR \u2013 Spanish<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/\" title=\"SERVICIOS \u2013 Spanish\">SERVICIOS \u2013 Spanish<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTALLERES \u2013 Spanish\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/emanuelenargi.com\/"},{"label":"FORMADOR &#8211; Spanish","link":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/"},{"label":"SERVICIOS &#8211; Spanish","link":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/"},{"label":"TALLERES &#8211; Spanish","link":"https:\/\/emanuelenargi.com\/index.php\/es\/formador-spanish\/servicios-spanish\/talleres-spanish\/"}],"_links":{"self":[{"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/pages\/7073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/comments?post=7073"}],"version-history":[{"count":55,"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/pages\/7073\/revisions"}],"predecessor-version":[{"id":9008,"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/pages\/7073\/revisions\/9008"}],"up":[{"embeddable":true,"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/pages\/7065"}],"wp:attachment":[{"href":"https:\/\/emanuelenargi.com\/index.php\/wp-json\/wp\/v2\/media?parent=7073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}